{"id":106410,"date":"2016-10-21T14:00:23","date_gmt":"2016-10-21T19:00:23","guid":{"rendered":"http:\/\/honeysanime.com\/es\/?p=106410"},"modified":"2017-12-20T02:24:11","modified_gmt":"2017-12-20T07:24:11","slug":"cheating-craft","status":"publish","type":"post","link":"https:\/\/honeysanime.com\/es\/cheating-craft\/","title":{"rendered":"Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!"},"content":{"rendered":"<div class=\"row no-gutters\">\n<div class=\"col-sm-5\">\n<div style=\"height:400px;\" class=\"overflow-hidden wrap-center-hv wrap-img-upcoming\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-300x425.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"300\" height=\"425\" class=\"aligncenter size-witdh-300 wp-image-97020\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-300x425.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-150x212.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-353x500.jpg 353w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual.jpg 438w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-sm-7 wrap-img-blur-upcoming\">\n<div style=\"height:400px;\" class=\"overflow-hidden wrap-center-hv\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-300x425.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"300\" height=\"425\" class=\"aligncenter size-witdh-300 wp-image-97020\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-300x425.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-150x212.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-353x500.jpg 353w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual.jpg 438w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n<div class=\"well overflow-hidden\">\n<h2 class=\"mt0 \">Cheating Craft<br \/>\n\t\t<\/h2>\n<div class=\"row\">\n<div class=\"col-xs-5 pr0\"><strong>G\u00e9nero:<\/strong><\/div>\n<div class=\"col-xs-7\">Acci\u00f3n, Escuela\n\t\t\t\t<\/div>\n<\/p><\/div>\n<hr class=\"hr-dashed mt10 mb10\">\n<div class=\"row\">\n<div class=\"col-xs-5 pr0\"><strong>Emisi\u00f3n:<\/strong><\/div>\n<div class=\"col-xs-7\">5 de octubre 2016\n\t\t\t\t<\/div>\n<\/p><\/div>\n<hr class=\"hr-dashed mt10 mb10\">\n<div class=\"row\">\n<div class=\"col-xs-5 pr0\"><strong>Estudio(s):<\/strong><\/div>\n<div class=\"col-xs-7\">BLADE\n\t\t\t\t<\/div>\n<\/p><\/div>\n<\/div><\/div>\n<\/div>\n<h1 class=\"mt60\"><i class=\"fa fa-fw fa-magic\"><\/i>Comentarios de Honey<\/h1>\n<div class=\"upcoming-anime\">\n<div class=\"wrap-balloon-speech mt30\">\n<div class=\"well well-news-quotation\">\n<div class=\"balloon-speech mb10 \">\n<div class=\"left-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/bee-prev.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-left\">\u00bf<strong>Acci\u00f3n<\/strong>? \u00bf<strong>Escuela<\/strong>?\u00bf Es este el nuevo <strong>Gakusen Toshi Asterisk<\/strong> o <strong>Hundred<\/strong>? \u00a1Dame m\u00e1s!<\/div>\n<\/div>\n<div class=\"balloon-speech mb10 \">\n<div class=\"right-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/honey-shrug.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-right\">No, la historia es m\u00e1s profunda que un chico que tiene que estar al lado de un grupo de mujeres casi desnudas y una trama muy delgada. Esto fue hecho por <strong>Haoliners<\/strong>. Ya sabes, hicieron <strong>Hitori no Shita: The Outcast el verano 2016<\/strong>. Este anime se siente un poco m\u00e1s como la realidad, en donde los estudiantes compiten por las calificaciones. O algo as\u00ed como <strong>trabajo en parejas, como en Luck & Logic<\/strong>.<\/div>\n<\/div>\n<div class=\"balloon-speech mb10 \">\n<div class=\"left-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/bee-jerk.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-left\">Ahhhhhhh. Entonces, espera ... aqu\u00ed dice que este es un <strong>anime corto<\/strong>, <strong>de 10 minutos por episodio<\/strong>, \u00a1y es otro <strong>anime chino<\/strong>!. \u00a1Cada vez hay m\u00e1s y m\u00e1s animes chinos cada temporada!<\/div>\n<\/div>\n<div class=\"balloon-speech mb10 \">\n<div class=\"right-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/bombon-yes1.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-right\">\u00a1Puedes apostarlo Bee-kun! Viene <strong>Bloodivores<\/strong> que es un anime de acci\u00f3n de vampiros, y tambi\u00e9n veremos <strong>Soul Buster<\/strong> que es un anime hist\u00f3rico de fantas\u00eda, as\u00ed que .... \u00a1al menos tendremos una gran variedad de nuevos animes chinos!<\/div>\n<\/div><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"mt60\" id=\"scroll-animedb-video\">\n<h1><i class=\"fa fa-fw fa-film\"><\/i>Video Promocional<\/h1>\n<div class=\"wrap-movie text-center\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class='youtube-player' width='560' height='315' src='https:\/\/www.youtube.com\/embed\/CTV5wIdUdy0?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent' allowfullscreen='true' style='border:0;' sandbox='allow-scripts allow-same-origin allow-popups allow-presentation'><\/iframe><\/span>\n\t<\/div>\n<\/div>\n<h1 class=\"mt60\"><i class=\"fa fa-fw fa-picture-o\"><\/i>Visuales<\/h1>\n<div class=\"well well-news-quotation mt30\">\n<div class=\"row\">\n<div class=\"col-xs-6 col-sm-3 pa0-xs\">\n\t\t\t<a href=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual.jpg\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual-225x350.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"225\" height=\"350\" class=\"aligncenter size-characeter-MAL-225 wp-image-97020\" \/><\/a>\t<\/p>\n<p>Visual 1<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"mt60\" id=\"scroll-animedb-synopsis\">\n<h1><i class=\"fa fa-fw fa-book\"><\/i>Sinopsis<\/h1>\n<div class=\"well well-white\">\n\t\tSituado en un mundo en el que la educaci\u00f3n determina tu valor como ser humano, pasar los ex\u00e1menes determina tus futuros \u00e9xitos. Desde una edad muy temprana, los ex\u00e1menes separan a los que pueden de los que no pueden. S\u00f3lo a los que pasan se les garantiza un futuro feliz, mientras que aquellos que no pasan no pueden esperar nada m\u00e1s que una vida dura. Sin embargo, nadie en este mundo dice \"oh, es simplemente porque no puedo estudiar\", ni nadie glorifica el camino de la vida infeliz. <\/p>\n<p>Con el fin de hacer que obtener buenas calificaciones, las personas han intentado casi todo bajo el sol. Los tramposos tambi\u00e9n han tratado de obtener las mejores notas al causar perturbaciones durante los ex\u00e1menes. En alg\u00fan momento a lo largo del camino, s\u00f3lo tener que estudiar y posteriormente pasar el examen desapareci\u00f3 como el \u00fanico m\u00e9todo y el campo de pruebas se ha convertido en un campo de batalla.<\/p>\n<p>Los que toman en serio sus estudios son \"tipo did\u00e1ctico\", mientras que los que hacen trampas son \"tipo tramposo\". Mientras que dejan a un lado las perturbaciones de los respectivos tipos did\u00e1cticos y los tramposos, en equipos de dos, aspiran a las puntuaciones m\u00e1s altas. Con el fin de evitar que los tipos did\u00e1cticos alcancen las puntuaciones m\u00e1s altas, los tipos tramposos lanzan ataques sin piedad en una batalla ardiente. <\/p>\n<p>Agrega a los procuradores del examen que no perdonan ning\u00fan tipo de fraudes \u00a1y el campo de pruebas se hace a\u00fan m\u00e1s ca\u00f3tico! <strong>Mumei<\/strong>, un estudiante de tipo tramposo y <strong>Koui<\/strong>, un estudiante de tipo did\u00e1ctico se enfrentan en una manera muy llamativa en esta historia sobre la intensa batalla para pasar este examen. <\/p><\/div>\n<\/div>\n<div class=\"mt60\" id=\"scroll-animedb-characters\">\n<h1><i class=\"fa fa-fw fa-smile-o\"><\/i>Personajes &amp; Seiyuus<\/h1>\n<div>\n<h2 class=\"mt0\">Mumei Shokatsu<br \/>\n\t<\/h2>\n<div class=\"mr20 pull-left\" style=\"width: 160px;\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Mumei-Shoukatsu-Cheating-Craft-225x350.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"225\" height=\"350\" class=\"aligncenter size-characeter-MAL-225 wp-image-97024\" \/>\n  <\/div>\n<p class=\"mb5\"><strong>Seiyuu: <\/strong>Tomohiro Yamaguchi<\/p>\n<hr class=\"hr-dashed\">\n<p><strong>Mumei<\/strong> fue criado para poder utilizar el <em>Shokatsu Senjutsu<\/em>. Con el fin de liberar a su padre injustamente preso, retar\u00e1 el examen de la licenciatura estatal de alta calidad.<\/p>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div>\n<h2 class=\"mt0\">Koui Ou<br \/>\n\t<\/h2>\n<div class=\"mr20 pull-left\" style=\"width: 160px;\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Koui-Ou-Cheating-Craft-225x350.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"225\" height=\"350\" class=\"aligncenter size-characeter-MAL-225 wp-image-97025\" \/>\n  <\/div>\n<p class=\"mb5\"><strong>Seiyuu: <\/strong>Rie Kugimiya<\/p>\n<hr class=\"hr-dashed\">\n<p><strong>Koui<\/strong> es prima de Mumei. Como compa\u00f1era de tipo did\u00e1ctico de Mumei, ella tambi\u00e9n entra a la academia Rinsen. Ella le saca el mejor provecho a su intelecto y desaf\u00eda el examen junto con Mumei.<\/p>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div>\n<h2 class=\"mt0\">Rinu Shuu<br \/>\n\t<\/h2>\n<div class=\"mr20 pull-left\" style=\"width: 160px;\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Rinu-Shuu-Cheating-Craft-225x350.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"225\" height=\"350\" class=\"aligncenter size-characeter-MAL-225 wp-image-97026\" \/>\n  <\/div>\n<p class=\"mb5\"><strong>Seiyuu: <\/strong>Daisuke Namikawa<\/p>\n<hr class=\"hr-dashed\">\n<p><strong>Rinu<\/strong> es compa\u00f1ero y rival de Mumei. \u00c9l est\u00e1 en b\u00fasqueda de un compa\u00f1ero fuerte con quien trabajar para aprobar el examen. Actualmente Rinu trabaja en una cafeter\u00eda a tiempo parcial.<\/p>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<div>\n<h2 class=\"mt0\">Haku Ryuu<br \/>\n\t<\/h2>\n<div class=\"mr20 pull-left\" style=\"width: 160px;\"><img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Haku-Ryuu-Cheating-Craft-225x350.jpg\"alt = \"Cheating-Craft-Key-Visual-300x425 Cheating Craft - El anime escolar de acci\u00f3n, \u00a1desata su video promocional!\" width=\"225\" height=\"350\" class=\"aligncenter size-characeter-MAL-225 wp-image-97027\" \/>\n  <\/div>\n<p class=\"mb5\"><strong>Seiyuu: <\/strong>Reina Ueda<\/p>\n<hr class=\"hr-dashed\">\n<p><strong>Haku<\/strong> es una hermosa chica que se sienta al frente del sal\u00f3n de clase. Como una estudiante ejemplar, aborrece a los que hacen trampa en los ex\u00e1menes. Ella desea ser como Mumei que ha recibido una puntuaci\u00f3n perfecta desde que entr\u00f3 a la academia. <\/p>\n<div class=\"clearfix\"><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"wrap-ad ad-middle mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Middle_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<div class=\"mt60\" id=\"scroll-animedb-detailed\">\n<table class=\"table-hot-spot\">\n<tr>\n<th style=\"width: 25%; vertical-align: center;\">Episodios<\/th>\n<td>12\n\t\t<\/td>\n<\/tr>\n<\/p>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%; vertical-align: center;\">Canciones<\/th>\n<td>\n<ul>\n<li><strong>Tema del Intro: <\/strong><em>Kasoku Suru Trial<\/em> por Kamen Joshi\n\t\t\t\t\t<\/li>\n<li><strong>Tema del Ending: <\/strong><em>Welcome future<\/em> por Aina Kusuda\n\t\t\t\t\t<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%; vertical-align: center;\">Adaptaci\u00f3n<\/th>\n<td>\n<div>\n\t\t\t\t<strong>Novela ligera China<br \/>\n\t\t\t\t<\/strong>\n\t\t\t<\/div>\n<div class=\"row\">\n<div class=\"col-sm-5 col-xs-12\">\n<div>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-sm-7\">\n<\/p><\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<th style=\"width: 25%; vertical-align: center;\">Personal\n\t\t\t\t<\/th>\n<td>\n<div>\n<ul>\n<li><strong>Creador original: <\/strong>Gemini Xin Luo\n\t\t\t\t\t\t<\/li>\n<li><strong>Director:  <\/strong>Keitarou Motonaga\n\t\t\t\t\t\t<\/li>\n<li><strong>Editing: <\/strong>Yoshiaki Kimura\n\t\t\t\t\t\t<\/li>\n<li><strong>Composici\u00f3n de serie:  <\/strong>Takamitsu Kouno\n\t\t\t\t\t\t<\/li>\n<li><strong>Dise\u00f1o de personaje:  <\/strong>Mai Mitsuura\n\t\t\t\t\t\t<\/li>\n<li><strong>Director de animaci\u00f3n:  <\/strong>Mai Matsuura, Kie Tanaka, Ryousuke Tanikawa\n\t\t\t\t\t\t<\/li>\n<li><strong>Director de sonido:  <\/strong>Yasunori Ebina\n\t\t\t\t\t\t<\/li>\n<li><strong>M\u00fasica:  <\/strong>Gou Sakabe\n\t\t\t\t\t\t<\/li>\n<\/ul><\/div>\n<div>\n<p>Para m\u00e1s informaci\u00f3n: <a href=\"http:\/\/cheating-craft.com\/\" target=\"_blank\" rel=\"noopener\">P\u00e1gina web oficial<\/a><\/p>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p class=\"text-right mt40\"><small>(Dale cr\u00e9ditos a Honey\u2019s Anime cuando uses nuestra descripci\u00f3n)<\/small><\/p>\n<div class=\"wrap-ad ad-bottom mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Bottom_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<p><script>\ndocument.addEventListener('copy', function(e) {\n\te.preventDefault();\n\tvar url = location.href;\n\tvar userAgent = window.navigator.userAgent.toLowerCase();<\/p>\n<p>\tif(url.match(\"\/es\/\")) {\n\t\tif (userAgent.match(\/(msie|MSIE)\/) || userAgent.match(\/(T|t)rident\/)) {\n\t\t\tvar text = document.selection.createRange().text;\n\t\t\twindow.clipboardData.setData('Text', text + \" (fuente: <a href='\" + url + \"'>Honey's Anime<\/a>)\"); \/\/ IE\n\t\t} else {\n\t\t\tvar text = window.getSelection();\n\t\t\te.clipboardData.setData('text\/plain', text + \" (fuente: <a href='\" + url + \"'>Honey's Anime<\/a>)\"); \/\/ Chrome, Firefox, safari\n\t\t}\n\t}else{\n\t\tif (userAgent.match(\/(msie|MSIE)\/) || userAgent.match(\/(T|t)rident\/)) {\n\t\t\tvar text = document.selection.createRange().text;\n\t\t\twindow.clipboardData.setData('Text', text + \" (source: <a href='\" + url + \"'>Honey's Anime<\/a>)\"); \/\/ IE\n\t\t} else {\n\t\t\tvar text = window.getSelection();\n\t\t\te.clipboardData.setData('text\/plain', text + \" (source: <a href='\" + url + \"'>Honey's Anime<\/a>)\"); \/\/ Chrome, Firefox, safari\n\t\t}\n\t}\n});\n<\/script><\/p>\n<style>\n<p>.upcoming-anime .balloon-speech .arrow-right{\n    width: 60%;\n    padding: 3%;\n    font-size: 15px !important;\nfloat:right;\nborder: 5px solid #efd592;  \n}<\/p>\n<p> .upcoming-anime .balloon-speech .arrow-left {\n width: 60%;\n    padding: 3%;\n    font-size: 15px !important;\nfloat:left;\nborder: 5px solid #efd592;  \n}<\/p>\n<p>.upcoming-anime .balloon-speech .left-image {\n    float: left;\n    width: 15%;\nmargin-right:30px;\n}<\/p>\n<p>.upcoming-anime .balloon-speech .right-image {\n    float: right;\n    width: 15%;\nmargin-left:30px;\n}<\/p>\n<p>.upcoming-anime .balloon-speech .arrow-left:before {\n    border-right-color: #efd592;\nborder-width: 20px;\n    margin-top: -20px;\n}<\/p>\n<p>.upcoming-anime .balloon-speech .arrow-right:before {\n    border-left-color: #efd592;\nborder-width: 20px;\n    margin-top: -20px;\n}<\/p>\n<\/style>\n","protected":false},"excerpt":{"rendered":"<p>Visual 1 Situado en un mundo en el que la educaci\u00f3n determina tu valor como ser humano, pasar los ex\u00e1menes determina tus futuros \u00e9xitos. Desde una edad muy temprana, los ex\u00e1menes separan a los que pueden de los que no pueden. S\u00f3lo a los que pasan se les garantiza un futuro feliz, mientras que aquellos [&hellip;]<\/p>\n","protected":false},"author":524,"featured_media":97020,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[244,239],"tags":[201,216],"themes":[935,751,763,746,946],"display":[],"seasonal":[],"jetpack_featured_media_url":"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/09\/Cheating-Craft-Key-Visual.jpg","jetpack_shortlink":"https:\/\/wp.me\/p5dDBg-rGi","_links":{"self":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/106410"}],"collection":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/users\/524"}],"replies":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/comments?post=106410"}],"version-history":[{"count":1,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/106410\/revisions"}],"predecessor-version":[{"id":177142,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/106410\/revisions\/177142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media\/97020"}],"wp:attachment":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media?parent=106410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/categories?post=106410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/tags?post=106410"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/themes?post=106410"},{"taxonomy":"display","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/display?post=106410"},{"taxonomy":"seasonal","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/seasonal?post=106410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}