{"id":156536,"date":"2017-06-28T21:40:12","date_gmt":"2017-06-29T02:40:12","guid":{"rendered":"http:\/\/honeysanime.com\/?p=156536\/"},"modified":"2017-11-14T02:23:32","modified_gmt":"2017-11-14T07:23:32","slug":"uchiage-hanabi-shita-kara-miruka-yoko-kara-miruka-pelicula-de-anime-estrena-su-video-promocional","status":"publish","type":"post","link":"https:\/\/honeysanime.com\/es\/uchiage-hanabi-shita-kara-miruka-yoko-kara-miruka-pelicula-de-anime-estrena-su-video-promocional\/","title":{"rendered":"Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional"},"content":{"rendered":"<aside class=\"exclude-from-excerpt\">\n<div class=\"twitter-tweet\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"ja\" dir=\"ltr\">DAOKO\u00d7\u7c73\u6d25\u7384\u5e2b\u306b\u3088\u308b\u4e3b\u984c\u6b4c\u3082\u767a\u8868\uff01\u300e\u6253\u3061\u4e0a\u3052\u82b1\u706b\u3001\u4e0b\u304b\u3089\u898b\u308b\u304b\uff1f\u6a2a\u304b\u3089\u898b\u308b\u304b\uff1f\u300f\u306e\u6700\u65b0\u6620\u50cf\u304c\u89e3\u7981 <a href=\"https:\/\/t.co\/zYvaxmnf30\">https:\/\/t.co\/zYvaxmnf30<\/a> <a href=\"https:\/\/t.co\/OzkORx1DN5\">pic.twitter.com\/OzkORx1DN5<\/a><\/p>\n<p>&mdash; MOVIE WALKER PRESS (@Movie__Walker) <a href=\"https:\/\/twitter.com\/Movie__Walker\/status\/879791500606939136?ref_src=twsrc%5Etfw\">27 de junio de 2017<\/a><\/p><\/blockquote>\n<\/div>\n<\/aside>\n<h2 class=\"border-text mt40\"><span><i class=\"fa fa-fw fa-bell\"><\/i>Lo que necesitas saber:  <\/span><\/h2>\n<ul class=\"ul-news\">\n<li>Esta es la nueva pel\u00edcula de anime del estudio Shaft, <strong>Uchiage hanabi, shita kara miruka? Yoko kara miruka?<\/strong> (Fuegos Artificiales, \u00bflos vemos desde abajo?, \u00bfo desde un lado?).<\/li>\n<li>Hoy, un nuevo visual ha sido revelado, el cual podemos ver en el tweet de arriba. Tambi\u00e9n tenemos el video promocional en el que se muestra m\u00e1s de la animaci\u00f3n y de las actuaciones de voz.<\/li>\n<li>El video promocional tambi\u00e9n le da a la audiencia un pedacito del tema de la canci\u00f3n, \"Uchiage Hanabi\" interpretado por <strong>DAOKO<\/strong>. \u00a1No te lo pierdas!<\/li>\n<\/ul>\n<p><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/g5SnDw55N9M\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p class=\"text-right\"><i class=\"fa fa-fw fa-search-plus\"><\/i>Fuente: <a href=\"http:\/\/www.uchiagehanabi.jp\/\" target=\"_blank\">P\u00e1gina web oficial<\/a><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-balloon-speech\">\n<div class=\"balloon-speech mb10 \">\n<div class=\"left-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/bee-music.jpg\"alt = \"bee-music Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-left\">\u00a1Me gusta lo que escucho de esta canci\u00f3n, se nota que esta pel\u00edcula ser\u00e1 muy buena!<\/div>\n<\/div>\n<div class=\"balloon-speech mb10 \">\n<div class=\"right-image\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/icon-ha-characters\/honey-happy1.jpg\"alt = \"bee-music Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional\" width=\"140\" height=\"140\" class=\"alignnone size-full\" \/><\/div>\n<div class=\"arrow-right\">\u00a1Aparentemente ellos van a a\u00f1adir elementos modernos a la historia original de la pel\u00edcula live action de 1993. Seguro ser\u00e1 buena!<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-ad ad-bottom mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Bottom_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/hibike-euphonium-anuncia-dos-peliculas-originales-y-revela-el-video-promocional\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"157\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png\" class=\"attachment-medium size-medium wp-post-image\"alt = \"bee-music Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-150x79.png 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-768x402.png 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-500x262.png 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-955x500.png 955w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-700x366.png 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-560x293.png 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/hibike-euphonium-anuncia-dos-peliculas-originales-y-revela-el-video-promocional\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Hibike! Euphonium anuncia DOS pel\u00edculas originales y revela el video promocional<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/haikyuu-revelan-el-visual-de-la-nueva-pelicula\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"157\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png\" class=\"attachment-medium size-medium wp-post-image\"alt = \"bee-music Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-150x79.png 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-768x402.png 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-500x262.png 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-955x500.png 955w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-700x366.png 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-560x293.png 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/haikyuu-revelan-el-visual-de-la-nueva-pelicula\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Haikyuu!! Revelan el visual de la nueva pel\u00edcula<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/regresan-las-aventuras-en-disboard-con-no-game-no-life-zero\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"157\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png\" class=\"attachment-medium size-medium wp-post-image\"alt = \"bee-music Uchiage hanabi, shita kara miruka? Yoko kara miruka?, pel\u00edcula de anime estrena su video promocional\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-300x157.png 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-150x79.png 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-768x402.png 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-500x262.png 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-955x500.png 955w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-700x366.png 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es-560x293.png 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/regresan-las-aventuras-en-disboard-con-no-game-no-life-zero\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Regresan las aventuras en Disboard con \"No Game No Life: Zero\"<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta es la nueva pel\u00edcula de anime del estudio Shaft, Uchiage hanabi, shita kara miruka? Yoko kara miruka? (Fuegos Artificiales, \u00bflos vemos desde abajo?, \u00bfo desde un lado?). Hoy, un nuevo visual ha sido revelado, el cual podemos ver en el tweet de arriba. Tambi\u00e9n tenemos el video promocional en el que se muestra m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":524,"featured_media":122073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[151],"tags":[],"themes":[925],"display":[],"seasonal":[],"jetpack_featured_media_url":"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/01\/eyecatch-cat-news-es.png","jetpack_shortlink":"https:\/\/wp.me\/p5dDBg-EIM","_links":{"self":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/156536"}],"collection":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/users\/524"}],"replies":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/comments?post=156536"}],"version-history":[{"count":2,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/156536\/revisions"}],"predecessor-version":[{"id":156541,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/156536\/revisions\/156541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media\/122073"}],"wp:attachment":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media?parent=156536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/categories?post=156536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/tags?post=156536"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/themes?post=156536"},{"taxonomy":"display","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/display?post=156536"},{"taxonomy":"seasonal","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/seasonal?post=156536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}