{"id":171537,"date":"2017-08-25T08:00:28","date_gmt":"2017-08-25T13:00:28","guid":{"rendered":"http:\/\/honeysanime.com\/?p=171537\/"},"modified":"2017-11-22T21:13:43","modified_gmt":"2017-11-23T02:13:43","slug":"el-flechazo-de-honey-sinbad-magi-sinbad-no-bouken","status":"publish","type":"post","link":"https:\/\/honeysanime.com\/es\/el-flechazo-de-honey-sinbad-magi-sinbad-no-bouken\/","title":{"rendered":"[El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)"},"content":{"rendered":"<p><!-- \n\n<div class=\"wrap-ad ad-top1 mb40\">[pc]\n\n<div class=\"unit-ad\">[ad_pc_article_top1_1]<\/div>\n\n\n\n<div class=\"unit-ad\">[ad_pc_article_top1_2]<\/div>\n\n[\/pc][sp][ad_sp_article_top1_1][\/sp]<\/div>\n\n --><\/p>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-300x423.jpg\"alt = \"Magi-Sinbad-dvd-300x423 [El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)\" width=\"300\" height=\"423\" class=\"aligncenter size-witdh-300 wp-image-171540\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-300x423.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-150x211.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-768x1082.jpg 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-500x704.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-355x500.jpg 355w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-700x986.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd-560x789.jpg 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-Sinbad-dvd.jpg 1065w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/B01EWSMLWK\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<h3 class=\"text-center fz20\">\u201cUn pa\u00eds que no aprecia a su gente no deber\u00eda existir\u201d<\/h3>\n<div class=\"well well-anime-basic-info\" id=\"scroll-1character-basic-info\">\n<ul>\n<li><strong>Episodios<\/strong>: 13<\/li>\n<li><strong>G\u00e9nero<\/strong>: Acci\u00f3n, Aventura, Fantas\u00eda, Magia, Shounen<\/li>\n<li><strong>Emisi\u00f3n<\/strong>: abril 2016 a julio 2016<\/li>\n<li><strong>Productores<\/strong>: Aniplex, Mainichi Broadcasting System, Shogakukan<\/li>\n<\/ul>\n<\/div>\n<div class=\"wrap-ad ad-top2 mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Top_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<h1><i class=\"fa fa-fw fa-star-o\"><\/i>Introducci\u00f3n a Magi: Sinbad no Bouken (Libre de spoilers)<\/h1>\n<p>\nLa trama comienza en la aldea Tison, un humilde poblado del Imperio Parthevia. All\u00ed naci\u00f3 <strong>Sinbad<\/strong>, un joven intr\u00e9pido y astuto que sue\u00f1a con explorar y conquistar el mundo, emprendiendo para ello un viaje a trav\u00e9s del oc\u00e9ano. \u00c9l es hijo de <strong>Badr<\/strong>, un antiguo soldado que dedic\u00f3 su vida al servicio del Imperio, pero que debi\u00f3 retirarse tempranamente tras perder una pierna. En su traves\u00eda, Sinbad vivir\u00e1 incre\u00edbles aventuras que pondr\u00e1n a prueba su ambici\u00f3n y car\u00e1cter. <em>Magi: Sinbad no Bouken<\/em> est\u00e1 ambientada en un mundo medieval en donde las monarqu\u00edas gobiernan con mano firme a una sociedad profundamente marcada por la lucha de clases. El anime est\u00e1 inspirado en Sinbad el marino, personaje del cuento infantil <em>\u201cLas mil y una noches\u201d<\/em>.<\/p>\n<h1><i class=\"fa fa-fw fa-user\"><\/i>Biograf\u00eda de Sinbad<\/h1>\n<p>\n<strong>Sinbad<\/strong> es un hombre de apariencia \u00e1rabe, alto, de larga cabellera y desarrollada musculatura de, aproximadamente, 30 a\u00f1os (al inicio de la serie ten\u00eda 14). Sus padres son <strong>Esra y Badr<\/strong>, este \u00faltimo un ex soldado del Imperio Parthevia. El chico en la aldea Tison vivi\u00f3 junto a sus padres hasta la adolescencia, cuando se march\u00f3 al este para unirse a la tribu de <em>Gladiadores Yambala<\/em>. Con estos guerreros aprendi\u00f3 la manipulaci\u00f3n del magoi, arte m\u00e1gica que permite controlar el poder de <em>Rukh<\/em> (fuerza del hogar de las almas). Con este enorme poder, Sinbad se embarc\u00f3 en un viaje a trav\u00e9s del mundo, en el cual form\u00f3 su propio ej\u00e9rcito de guerreros y fund\u00f3 su propio reino: Sindria. Gracias a sus heroicas aventuras se gan\u00f3 el apodo de \u201crey de los siete mares\u201d.\n<\/p>\n<h1><i class=\"fa fa-fw fa-magic\"><\/i>Caracter\u00edsticas m\u00e1s destacadas de Sinbad<\/h1>\n<div class=\"wrap-unit mt40\" id=\"scroll-1character-unit1\">\n<h2 class=\"border-text\"><span>1. Un joven nacido para gobernar<\/span><\/h2>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<aside class=\"exclude-from-excerpt\">\n<div class=\"twitter-tweet\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"ja\" dir=\"ltr\">\u300e\u30de\u30ae \u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\u306e\u5192\u967a\u300f\u7b2c9\u8a71\u300c\u6e05\u6d44\u306e\u5730\u30b5\u30b5\u30f3\u300d\u306e\u3042\u3089\u3059\u3058\u3092\u516c\u958b\u3057\u307e\u3057\u305f\uff01 <a href=\"https:\/\/t.co\/2hpuVFZzU9\">https:\/\/t.co\/2hpuVFZzU9<\/a>  \u3064\u3044\u306b\u81ea\u5206\u306e\u5546\u4f1a\u3092\u7acb\u3061\u4e0a\u3052\u305f\u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\u305f\u3061\u306f\u6e05\u6d44\u306e\u5730\u30b5\u30b5\u30f3\u3078\uff01 \u3042\u306e\u30ad\u30e3\u30e9\u304c\u3064\u3044\u306b\u767b\u5834\uff01 <a href=\"https:\/\/twitter.com\/hashtag\/magi?src=hash&amp;ref_src=twsrc%5Etfw\">#magi<\/a> <a href=\"https:\/\/t.co\/A9vWb1tr0I\">pic.twitter.com\/A9vWb1tr0I<\/a><\/p>\n<p>&mdash; TV\u30a2\u30cb\u30e1\u300c\u30de\u30ae \u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\u306e\u5192\u967a\u300d (@project_magi) <a href=\"https:\/\/twitter.com\/project_magi\/status\/740836734460657664?ref_src=twsrc%5Etfw\">9 de junio de 2016<\/a><\/p><\/blockquote>\n<\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nA pesar de ser apenas un adolescente al inicio de su traves\u00eda, <strong>Sinbad<\/strong> siempre demostr\u00f3 ser una persona de temple y valor, con una innata capacidad de liderazgo. A los 14 a\u00f1os fue capaz de salir a conquistar un calabozo y de embarcarse \u2014por voluntad propia\u2014 en una misi\u00f3n de que lo llev\u00f3, incluso, a fundar y gobernar su propio pa\u00eds. Gracias a su fuerza f\u00edsica y a su agudeza mental, nuestro chico se las ingeni\u00f3 para derrotar a monarcas como el rey <strong>Darius<\/strong> y la reina <strong>Mira<\/strong>, esto luego de reunir un importante ej\u00e9rcito de guerreros que fue reclutando durante su traves\u00eda marina.<\/p>\n<p>Por si fuera poco, Sinbad se ha ganado la fama y el respeto de los Siete Mares, luego de conquistar sus siete celdas, siendo la primera persona en lograr semejante proeza. Siempre sobrio cuando la ocasi\u00f3n lo amerita, Sinbad es visto como un monarca justo y honorable en todo el mundo. Su labor como soberano de Sindria y luego como l\u00edder de la Alianza Internacional ha sido clave para la consolidaci\u00f3n de la <em>Alianza de los Siete Mares<\/em>, organizaci\u00f3n en donde ha logrado agrupar a todas las superpotencias en pro de preservar la paz y la justicia en el mundo.\n    <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<div class=\"wrap-unit mt40\" id=\"scroll-1character-unit2\">\n<h2 class=\"border-text\"><span>2. Seductor por excelencia<\/span><\/h2>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-560x356.jpg\"alt = \"Magi-Sinbad-dvd-300x423 [El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)\" width=\"560\" height=\"356\" class=\"aligncenter size-width-560 wp-image-137973\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-560x356.jpg 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-150x95.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-300x191.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-768x488.jpg 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-500x318.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga.jpg 787w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/Magi-Sinbad-no-Bouken-manga-700x445.jpg 700w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/>      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4091246923\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nEsto es lo que, definitivamente, nos ha derretido de <strong>Sinbad<\/strong>. Sus ojos color avellana endulzan una mirada fija y cautivadora que, sencillamente, hipnotiza a cualquiera. Este amo de los oc\u00e9anos no solo tiene la facilidad de conquistar territorios, sino tambi\u00e9n corazones. De barco en barco, de puerto en puerto, Sinbad tiene lo necesario para enamorar a cuanta doncella se cruce en su camino.<\/p>\n<p>Uno de sus ganchos, adem\u00e1s de su atractivo f\u00edsico, es la labia. Sinbad es de esas personas que sabe cu\u00e1ndo y c\u00f3mo decir las cosas que los dem\u00e1s quieren o\u00edr, algo que le ha sido muy \u00fatil para reclutar aliados en sus expediciones; por ello, es un excelente negociador y pol\u00edtico. Sinbad, simplemente, tiene el paquete completo: astucia, belleza y buen l\u00e9xico. \u00bfQu\u00e9 m\u00e1s pueden pedir, chicas?<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<div class=\"wrap-unit mt40\" id=\"scroll-1character-unit3\">\n<h2 class=\"border-text\"><span>3. Siempre se preocupa por los dem\u00e1s<\/span><\/h2>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<aside class=\"exclude-from-excerpt\">\n<div class=\"twitter-tweet\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"ja\" dir=\"ltr\">\u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\uff06\u30df\u30b9\u30c8\u30e9\u30b9\uff06\u30b8\u30e3\u30fc\u30d5\u30a1\u30eb\u304c\u6b4c\u3046\u30ad\u30e3\u30e9\u30af\u30bf\u30fc\u30bd\u30f3\u30b0\u300eLife goes on\u300f\u5148\u884c\u8a66\u8074\u3092\u30db\u30fc\u30e0\u30da\u30fc\u30b8\u3067\u5b9f\u65bd\u4e2d\uff01 8\u670824\u65e5\u767a\u58f2\u300eCOMPLETE BOX\u300f\u306b\u53ce\u9332\uff01<a href=\"https:\/\/t.co\/ZLn3nMJr1A\">https:\/\/t.co\/ZLn3nMJr1A<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/magi?src=hash&amp;ref_src=twsrc%5Etfw\">#magi<\/a> <a href=\"https:\/\/t.co\/V4MXjni8He\">pic.twitter.com\/V4MXjni8He<\/a><\/p>\n<p>&mdash; TV\u30a2\u30cb\u30e1\u300c\u30de\u30ae \u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\u306e\u5192\u967a\u300d (@project_magi) <a href=\"https:\/\/twitter.com\/project_magi\/status\/752055499768508416?ref_src=twsrc%5Etfw\">10 de julio de 2016<\/a><\/p><\/blockquote>\n<\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nAunque no es muy com\u00fan que los conquistadores sean nobles, <strong>Sinbad<\/strong> rompe con este estereotipo. Su capacidad de liderazgo es tan fuerte como su sentido de lealtad: para \u00e9l, sus s\u00fabditos y compa\u00f1eros de batalla son como su familia, siempre est\u00e1 al pendiente de la felicidad de sus allegados. <\/p>\n<p>Del mismo modo, como monarca nunca descuida a su pueblo, y siente que lo m\u00e1s importante es satisfacer las necesidades de la gente. Para Sinbad, \u201cel pa\u00eds existe para proteger al pueblo que vive en \u00e9l. No es correcto llevarlos a la guerra para que mueran, as\u00ed como tampoco es necesario que exista un pa\u00eds que no protege a su pueblo\u201d. \u00bfNo es genial que piense as\u00ed? Por ello, nuestro chico es un rey amado por todos.<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<div class=\"wrap-unit mt40\" id=\"scroll-1character-unit4\">\n<h2 class=\"border-text\"><span>4. Uno de los pocos en dominar el Magoi<\/span><\/h2>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div>\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-300x371.jpg\"alt = \"Magi-Sinbad-dvd-300x423 [El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)\" width=\"300\" height=\"371\" class=\"aligncenter size-witdh-300 wp-image-171542\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-300x371.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-150x186.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-768x950.jpg 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-500x619.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-404x500.jpg 404w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-700x866.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd-560x693.jpg 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Magi-dvd.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/B00J16IUDI\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nGracias al entrenamiento con la tribu <em>Yambala<\/em>, <strong>Sinbad<\/strong> adquiri\u00f3 una habilidad que, en principio, solo dominan los magos. El <em>magoi<\/em> es una energ\u00eda que reside en el cuerpo, la cual proviene del Rukh, el hogar de las almas. Esta es la energ\u00eda utilizada por los magos para potenciar armas y articular conjuros. Del mismo modo, permite dominar los elementos de la naturaleza (como el agua y el fuego) para generar potentes ataques.<\/p>\n<p>El m\u00e9todo perfeccionado por Sinbad para dominar este poder consiste en controlar la energ\u00eda interna del cuerpo y proyectarla con las manos. Asimismo, este chico es capaz de contrarrestar el <em>magoi<\/em> de sus oponentes, domin\u00e1ndolo con sus manos y neg\u00e1ndoles la posibilidad de utilizarlo. Esta habilidad debe usarse con prudencia si no se es mago, ya que produce un enorme desgaste f\u00edsico en el individuo que puede generar sangrados profusos, desmayos e, incluso, la muerte. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<div class=\"wrap-unit mt40\" id=\"scroll-1character-unit5\">\n<h2 class=\"border-text\"><span>5. Con Sinbad la diversi\u00f3n nunca faltar\u00e1<\/span><\/h2>\n<div align=\"center\" class=\"mt40\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<aside class=\"exclude-from-excerpt\">\n<div class=\"twitter-tweet\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"ja\" dir=\"ltr\">\u30b7\u30f3\u30c9\u30d0\u30c3\u30c9(\u5c0f\u91ce\u5927\u8f14)\uff06\u30df\u30b9\u30c8\u30e9\u30b9(\u7fbd\u591a\u91ce\u6e09)\uff06\u30b8\u30e3\u30fc\u30d5\u30a1\u30eb(\u6afb\u4e95\u5b5d\u5b8f)\u304c\u6b4c\u3046\u30ad\u30e3\u30e9\u30bd\u30f3\u300eLife goes on\u300f\u5148\u884c\u8a66\u8074\u5b9f\u65bd\u4e2d\uff01 8\/24\u300eCOMPLETE BOX\u300f\u306b\u30d5\u30eb\u5c3a\u53ce\u9332\uff01<a href=\"https:\/\/t.co\/ZLn3nMJr1A\">https:\/\/t.co\/ZLn3nMJr1A<\/a> <a href=\"https:\/\/t.co\/DRpilRU8Zw\">pic.twitter.com\/DRpilRU8Zw<\/a><\/p>\n<p>&mdash; TV\u30a2\u30cb\u30e1\u300c\u30de\u30ae \u30b7\u30f3\u30c9\u30d0\u30c3\u30c9\u306e\u5192\u967a\u300d (@project_magi) <a href=\"https:\/\/twitter.com\/project_magi\/status\/753430682236444672?ref_src=twsrc%5Etfw\">14 de julio de 2016<\/a><\/p><\/blockquote>\n<\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nSi hay algo que define a <strong>Sinbad<\/strong> es su gusto por las fiestas. A \u00e9l le encanta divertirse, siempre con lugar para comer y emborracharse hasta la saciedad luego de una batalla, como buen marinero. De hecho, su gusto por el alcohol y las mujeres hermosas hicieron que cayera en la depravaci\u00f3n total, motivo por el cual estuvo a punto de dejar la corona de Sindria. <\/p>\n<p>Por suerte, el joven monarca pudo rehabilitarse y volver al camino de la cordura, conduciendo de forma exitosa la Compa\u00f1\u00eda de Comercio de su reino y siendo pieza clave en el desarrollo de la <em>Alianza de los Siete Mares<\/em=>. Sin embargo, su esp\u00edritu festivo sigue intacto, y Sinbad siempre lleva la vida de forma descomplicada, con una actitud positiva y relajada. Mejor acompa\u00f1ada, no puedo estar. \u00bfNo les parece?<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<h2>Palabras finales<\/h2>\n<div id=\"scroll-1character-end\">\n<p>\nComo todo lo bueno dura poco, hasta aqu\u00ed llega nuestro repaso por lo mejor de este amo de los oc\u00e9anos, un rey a prueba de todo cuya personalidad y poder no se ven todos los d\u00edas. \u00bfLes gust\u00f3 este caramelito, mis amores? Ojal\u00e1 hayan quedado satisfechos con esta porci\u00f3n de miel, pero no se preocupen, que pronto volveremos con alg\u00fan otro flechazo para ustedes, nuestros amados lectores. \u00a1Hasta la pr\u00f3xima!  <\/p>\n<\/div>\n<div class=\"wrap-author well mt60\" id=\"wrap-author-075\">\n<div class=\"row\">\n<div class=\"col-xs-12 col-sm-4 col-md-3\">\n<div class=\"wrap-author-image pull-left mr15\">\n<div class=\"author-box\">\n<div class=\"wrap-centered\">\n<div class=\"wrap-centered-content\">\n<div class=\"wrap-img-overlay\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/author-profile-image\/075.jpg\" width=\"120px\" height=\"120px\"alt = \"Magi-Sinbad-dvd-300x423 [El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)\"><\/p>\n<div class=\"wrap-text-overlay overlay-\">\n<p class=\"sfont text-overlay\">Escritor<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clearfix hidden-xs\"><\/div>\n<p class=\"author-social mt10 mb0 mt6-xs\"><a href=\"https:\/\/twitter.com\/LabradorGeorge\" target=\"_blank\" rel=\"noopener\" aria-label=\"link to author twitter\"><i class=\"fa fa-twitter\"><\/i><\/a><a href=\"https:\/\/www.instagram.com\/georgelabrador\/\" target=\"_blank\" rel=\"noopener\" aria-label=\"link to author instagram\"><i class=\"fa fa-instagram\"><\/i><\/a><\/p>\n<\/div>\n<div class=\"col-xs-12 col-sm-8 col-md-9\">\n<div>\n<p><i class=\"fa fa-fw fa-pencil\"><\/i>Autor: <em>Le\u00f3n de Dios<\/em><\/p>\n<\/div>\n<div>\n<p class=\"author-profile fz9\">\u00a1Hola a todos! Soy George, mejor conocido como Le\u00f3n de Dios. Mis dos pasiones, aunque seguramente ya las conocen, son el anime y la escritura; gracias a Dios he podido combinarlas y regalarles un poco de lo que tanto amo. Cuando no estoy escribiendo o viendo una y otra vez mis animes favoritos, me dedico a mis estudios y al f\u00fatbol. Lo s\u00e9, soy una extra\u00f1a combinaci\u00f3n entre otaku y deportista, orgullosamente.<\/p>\n<p class=\"fz9\"><a href=\"https:\/\/honeysanime.com\/es\/author\/leon-de-dios\/\"><i class=\"fa fa-fw fa-pencil\"><\/i>Art\u00edculos escritos<\/a><\/p>\n<p class=\"fz9\"><a href=\"https:\/\/honeysanime.com\/es\/los-5-mejores-animes-segun-leon-de-dios-escritor-de-honeys-anime\/\"><i class=\"fa fa-fw fa-star\"><\/i><b>Los 5 mejores animes<\/b> seg\u00fan Le\u00f3n de Dios<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-ad ad-bottom mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Bottom_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/los-10-personajes-mas-rudos-de-magi-sinbad-no-bouken\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"228\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-300x228.jpg\" class=\"attachment-medium size-medium wp-post-image\"alt = \"Magi-Sinbad-dvd-300x423 [El flechazo de Honey] 5 caracter\u00edsticas destacadas de Sinbad (Magi: Sinbad no Bouken)\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-300x228.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-150x114.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-500x379.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-659x500.jpg 659w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/07\/Magi-Sinbad-no-Bouken-Wallpaper-20160719230705-560x425.jpg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/los-10-personajes-mas-rudos-de-magi-sinbad-no-bouken\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Los 10 personajes m\u00e1s rudos de Magi: Sinbad no Bouken<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cUn pa\u00eds que no aprecia a su gente no deber\u00eda existir\u201d Episodios: 13 G\u00e9nero: Acci\u00f3n, Aventura, Fantas\u00eda, Magia, Shounen Emisi\u00f3n: abril 2016 a julio 2016 Productores: Aniplex, Mainichi Broadcasting System, Shogakukan Introducci\u00f3n a Magi: Sinbad no Bouken (Libre de spoilers) La trama comienza en la aldea Tison, un humilde poblado del Imperio Parthevia. All\u00ed naci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":845,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[266,155],"tags":[229],"themes":[919,738],"display":[],"seasonal":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5dDBg-ICJ","_links":{"self":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/171537"}],"collection":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/users\/845"}],"replies":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/comments?post=171537"}],"version-history":[{"count":3,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/171537\/revisions"}],"predecessor-version":[{"id":172875,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/171537\/revisions\/172875"}],"wp:attachment":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media?parent=171537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/categories?post=171537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/tags?post=171537"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/themes?post=171537"},{"taxonomy":"display","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/display?post=171537"},{"taxonomy":"seasonal","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/seasonal?post=171537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}