{"id":173103,"date":"2017-08-30T12:00:51","date_gmt":"2017-08-30T17:00:51","guid":{"rendered":"http:\/\/honeysanime.com\/?p=173103\/"},"modified":"2017-11-22T21:12:05","modified_gmt":"2017-11-23T02:12:05","slug":"los-10-mejores-personajes-disenados-por-arina-tanemura","status":"publish","type":"post","link":"https:\/\/honeysanime.com\/es\/los-10-mejores-personajes-disenados-por-arina-tanemura\/","title":{"rendered":"Los 10 mejores personajes dise\u00f1ados por Arina Tanemura"},"content":{"rendered":"<p><!-- \n\n<div class=\"wrap-ad ad-top1 mb40\">[pc]\n\n<div class=\"unit-ad\">[ad_pc_article_top1_1]<\/div>\n\n\n\n<div class=\"unit-ad\">[ad_pc_article_top1_2]<\/div>\n\n[\/pc][sp][ad_sp_article_top1_1][\/sp]<\/div>\n\n --><\/p>\n<div align=\"center\" id=\"scroll-character-top-image\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/time-stranger-kyoko-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"347\" height=\"500\" class=\"aligncenter size-full wp-image-171111\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/time-stranger-kyoko-manga.jpg 347w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/time-stranger-kyoko-manga-150x216.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/time-stranger-kyoko-manga-300x432.jpg 300w\" sizes=\"(max-width: 347px) 100vw, 347px\" \/>\n    <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4086195097\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/div>\n<div class=\"wrap-unit mt40\" id=\"scroll-characters-introduction\">\n<p>\nArina Tanemura es una conocida artista de manga que se ha hecho f\u00e1cilmente reconocible por su estilo detallado de dibujo y su inteligente uso de la pantalla de tonos. Desde su primera serie, I.O.N., tambi\u00e9n ha hecho renombre como escritora de historias rom\u00e1nticas que tienen un poquito extra de misterio, y a veces hasta finales sorpresivos. <\/p>\n<p>Y por que sus historias no son tan sencillas como \u201cchico conoce a chica, se enamoran\u201d, tienen intriga, misterio y a veces rencores que duran por m\u00e1s de dos generaciones.  Muestra el lado oscuro de la obsesi\u00f3n, y las consecuencias de la soledad y el amor no correspondido. No s\u00f3lo eso, logra hacerlo con un reparto muy interesante de personajes, que van de los inocentes e ingenuos, a los malignos y astutos. <\/p>\n<p>As\u00ed que aqu\u00ed tenemos a los 10 mejores personajes dise\u00f1ados por Arina Tanemura, tanto por su apariencia interesante como por sus historias profundas. <\/p>\n<\/div>\n<div class=\"wrap-ad ad-top2 mt40 mb40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Top_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-unit\" id=\"scroll-character-unit1\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>10. Takuto Kira de Full moon wo Sagashite<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-475x500.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"475\" height=\"500\" class=\"aligncenter size-height-500 wp-image-146941\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-475x500.jpg 475w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-150x158.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-300x315.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-500x526.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-700x736.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper-560x589.jpg 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/05\/Full-Moon-wo-Sagashite-wallpaper.jpg 736w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4089053862\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 7 <\/li>\n<li>Publicaci\u00f3n:  2001 - 2004 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\nUno de los shinigami que fue asignado para guiar el alma de <strong>Mitsuki<\/strong> en <em>Full moon o Sagashite<\/em>. Normalmente lo vemos usando una gorra con orejas de gato, y una mochila con alas que necesita para volar, ya que es un shinigami en entrenamiento. Sin embargo, cuando logra alcanzar a Mitsuki, siente que tiene una raz\u00f3n para sobrevivir un poquito m\u00e1s as\u00ed que decide usar sus poderes para transformarla en la cantante <strong>Fullmoon<\/strong>, sobre las protestas de su compa\u00f1era <strong>Meroko<\/strong> porque esa era la primera se\u00f1al de que <strong>Takuto<\/strong> se estaba enamorando de una humana. Si bien eso no est\u00e1 en contra las reglas, si podr\u00eda terminar rompiendo la regla m\u00e1s importante: No se debe salvar una vida humana. <\/p>\n<p>Es cuando descubrimos que Takuto, en el pasado, fue humano, cuando las cosas se ponen m\u00e1s interesantes: El era el cantante principal de <em>ROUTE:L<\/em>, a banda a la que el padre de Mitsuki y su doctor pertenec\u00edan. Sin embargo, justo como Mitsuki necesita que le quiten las cuerdas vocales, un tumor en su garganta le quito la voz. Por esto, intento matarse saltando desde el techo del hospital, y qued\u00f3 en coma por dos a\u00f1os. Lo que ocurre despu\u00e9s es parte del final, pero explica porque Takuto es tan interesante y gana el d\u00e9cimo lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit2\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>9. Chikage Deguchi de Idol Dreams<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Idol-Dreams-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"333\" height=\"500\" class=\"aligncenter size-full wp-image-171106\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Idol-Dreams-manga.jpg 333w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Idol-Dreams-manga-150x225.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Idol-Dreams-manga-300x450.jpg 300w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.com\/dp\/1421582562\/?tag=hone01d-20\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-fw fa-amazon\"><\/i>Buy now<\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 4 <\/li>\n<li>Publicaci\u00f3n: 2013 \u2013 contin\u00faa <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\nLa pobre <strong>Chikage<\/strong> tiene la crisis de la mediana edad para acabar con todas las crisis de la mediana edad. Acaba de cumplir 31 a\u00f1os, y est\u00e1 convencida de que su vida ha sido un desperdicio desde que dej\u00f3 la preparatoria cuando era popular, era la representante de la clase, y ten\u00eda pretendientes a su alrededor. Ahora que es adulta, no es popular, nadie la nota, y de hecho a\u00fan es virgen, algo que la hace ser blanco de algunas de las peores bromas de la oficina. Esto hace que llore en su reuni\u00f3n de preparatoria cuando se da cuenta de que no importa cu\u00e1nto trabaje, nunca estar\u00e1 donde quer\u00eda estar. Entonces un amigo de su juventud la interrumpe, pues tiene una droga experimental a su disposici\u00f3n y ahora Chikage puede volver a tener 15 a\u00f1os. <\/p>\n<p>Ahora, Chikage no regresa en el tiempo. No, s\u00f3lo se vuelve a ver de 15 a\u00f1os y decide caminar por la ciudad disfrutando su juventud temporal. Esto significa que por supuesto es confundida por una modelo, y termina grabando un comercial con uno de los cantantes m\u00e1s populares de Jap\u00f3n. Esto significa que por supuesto, lo tiene que hacer de nuevo. \u00bfC\u00f3mo puede balancear su vida de ensue\u00f1o como quincea\u00f1era con su vida real a los 31? Esa dicotom\u00eda es lo que hace que Chikage sea interesante. No es una adolescente cometiendo errores por primera vez, es una adulta que sabe m\u00e1s de la vida de lo que la gente cree, pero al mismo tiempo, se siente como un pez fuera del agua. <\/p>\n<p>Su doble vida, y su ternura constante a los 31 y a los 15, hacen que Chikage gane el noveno lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit3\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>8. Fuzuki Koyama de Full Moon wo Sagashite<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n      <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 7 <\/li>\n<li>Publicaci\u00f3n: 2001- 2004 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\nLas abuelas que deben cuidar a sus nietos tienden a tener dos extremos. O los consienten a morir, o son tan estrictas que sus nietos a veces terminan deseando que uno de los dos no hubiera nacido nunca. <strong>Fuzuki<\/strong> al principio cae en la segunda categor\u00eda. Recogi\u00f3 a su nieta cuando <strong>Mitsuki<\/strong> ten\u00eda diez a\u00f1os, pero desde entonces su relaci\u00f3n siempre fue fr\u00eda, pr\u00e1cticamente nunca se hablaban a menos que Fuzuki quisiera prohibirle a Mitsuki cantar en la casa. As\u00ed que al principio, Fuzuki parece la abuela estereot\u00edpica que odia todo lo que es divertido. <\/p>\n<p>Pero cuando Mitsuki huye para ser <strong>Fullmoon<\/strong>, Fuzuki comienza a darse cuenta de que ha sido demasiado extrema con su odio por la m\u00fasica. Si, tiene sus razones: desde su punto de vista, la m\u00fasica le ha quitado a todas las personas que ha amado. Su mejor amiga cuando eran m\u00e1s j\u00f3venes, cuando se enamoraron del mismo hombre. Cuando \u00e9l eligi\u00f3 a Fuzuki, ella no pudo aceptar porque no quer\u00eda que su amiga sufriera, pero ella malinterpret\u00f3 su despedida, y se suicid\u00f3. El joven era m\u00fasico, y desde entonces, Fuzuki odia la m\u00fasica. <\/p>\n<p>Por este pasado dram\u00e1tico, y su deseo de cambiar para su nieta, Fuzuki se gana el octavo lugar de la lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit4\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>7. Access Time de Kamikaze Kaitou Jeanne<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Access-Time-Kamikaze-Kaitou-Jeanne-manga-300x427.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"300\" height=\"427\" class=\"aligncenter size-witdh-300 wp-image-171108\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Access-Time-Kamikaze-Kaitou-Jeanne-manga-300x427.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Access-Time-Kamikaze-Kaitou-Jeanne-manga-150x214.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Access-Time-Kamikaze-Kaitou-Jeanne-manga.jpg 351w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4088551486\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes:  7 <\/li>\n<li>Publicaci\u00f3n:  1997 - 2000 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Access Time<\/strong> es un \u00c1ngel Oscuro, un \u00c1ngel que a\u00fan necesita hacer buenas obras para conseguir el t\u00edtulo de \u00c1ngel completo. Al mismo tiempo es el compa\u00f1ero de <strong>Kaitou Sinbad<\/strong>, el que permite que <strong>Chiaki<\/strong> se transforme, y quien le dice donde van a atacar los demonios. Y as\u00ed como Chiaki est\u00e1 enamorado de <strong>Maron\/Jeanne<\/strong>, Access Time est\u00e1 enamorado de la compa\u00f1era angelical de Maron, la hermosa <strong>Fin Fish<\/strong>. Desafortunadamente para \u00e9l, sus sentimientos no son correspondidos sin importar cu\u00e1nto insiste e intenta llamar la atenci\u00f3n del otro \u00e1ngel.  <\/p>\n<p>Y aqu\u00ed est\u00e1 la tragedia de Access, puesto que la raz\u00f3n por la que Finn Fish no lo quiere no es s\u00f3lo porque es muy insistente e inseguro. No, es porque ella tambi\u00e9n tiene un secreto que podr\u00eda lastimarlo, y a \u00e9l eso no le importa. Es muy necio en su lealtad, y tan enamorado que ni la muerte  y la reencarnaci\u00f3n puede alejarlo de su amada. Aparte de eso, Access tiene un dise\u00f1o muy notable, con cabello y alas negras que se ve a\u00fan mejor cuando logra conseguir el estado de \u00c1ngel Completo. Es por eso que Access Time tiene el s\u00e9ptimo lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit5\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>6.  Maika Kamiya de The Gentleman\u2019s Alliance Cross<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n      <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 11 <\/li>\n<li>Publicaci\u00f3n: 2004 -2008 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Maika Kamiya<\/strong> no ha tenido una vida f\u00e1cil. Debido a la tradici\u00f3n de su familia y su escuela, en lugar de casarse con su novio de preparatoria <strong>Itsuki Otomiya<\/strong>, fue forzada a ser la novia y casarse con <strong>Kazuhito Kamiya<\/strong>, pues sin ese matrimonio, su familia hubiera ca\u00eddo en la ruina y ella no pod\u00eda permitirlo. As\u00ed que se cas\u00f3, a pesar de que a\u00fan amaba a Itsuki y le dijo que la boda fue s\u00f3lo para guardar apariencias.  Nunca se enter\u00f3 de que la raz\u00f3n por la que la forzaron a casarse fue porque su esposo hizo trampa en las elecciones escolares, literalmente para alejarla del lado de Itsuki, pero si lleg\u00f3 a sentir l\u00e1stima por su esposo, ya que descubri\u00f3 que era un hombre muy solitario.<\/p>\n<p>Maika fue la madre de todos los hijos de Kazuhito, <strong>Haine, Komaki y Tachibana<\/strong>, y se hizo a un lado cuando Kazuhito decidi\u00f3 \u201cVender\u201d a Haine para que fuera la hija de Itsuki por la cantidad de 50 millones de yen.  Fue entonces cuando descubri\u00f3 que \u00e9l siempre supo que Haine no era su hija, sino hija de Itsuki. Al ver su secreto a la luz, Maika sufri\u00f3 un colapso mental que la mand\u00f3 al hospital, lejos de todos sus hijos. Uno puede imaginarse que esto fue en parte por sus sentimientos encontrados por su esposo e Itsuki, y el no poder reconciliarlo, por lo que prefiri\u00f3 apagar su cerebro por un rato.  <\/p>\n<p>Como esto la hace un personaje incre\u00edblemente interesante y complejo, le damos el sexto lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-ad ad-middle \">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Middle_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-unit\" id=\"scroll-character-unit6\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>5. Maguri Tsujimiya de The Gentleman\u2019s Alliance Cross<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maguri-Tsujimiya-The-Gentleman\u2019s-Alliance-Cross-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"321\" height=\"500\" class=\"aligncenter size-full wp-image-171109\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maguri-Tsujimiya-The-Gentleman\u2019s-Alliance-Cross-manga.jpg 321w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maguri-Tsujimiya-The-Gentleman\u2019s-Alliance-Cross-manga-150x234.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maguri-Tsujimiya-The-Gentleman\u2019s-Alliance-Cross-manga-300x467.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maguri-Tsujimiya-The-Gentleman\u2019s-Alliance-Cross-manga-225x350.jpg 225w\" sizes=\"(max-width: 321px) 100vw, 321px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4088566815\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 11 <\/li>\n<li>Publicaci\u00f3n:  2004 \u2013 2008 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Maguri<\/strong> es un chico muy alegre, el vicepresidente del Consejo Estudiantil y el mejor amigo del presidente, a quien conoce como <strong>Shizumasa Togu<\/strong>: aunque en realidad, Shizumasa es <strong>Takanari Togu<\/strong> \u2013esto es algo complicado, y gran parte de todo el argumento del manga. Lo que mucha gente no sabe de Maguri es que tiene un lado muy sensible, a pesar de ser parte de una familia conectada con los <em>yakuza<\/em>. Esta es la raz\u00f3n por la que Maguri aprendi\u00f3 desde la infancia que eres leal a tus amigos, sin importar las consecuencias. <\/p>\n<p>A pesar de que es el \u00fanico miembro del consejo que no besa a <strong>Haine<\/strong> en alg\u00fan punto de la historia, al principio asegura estar enamorado de ella. Sin embargo, es muy bueno escondiendo sus sentimientos; despu\u00e9s de todo fingi\u00f3 ser el novio de Takanari cuando este fing\u00eda ser Shizumasa, para que las chicas dejaran a Takanari solo. Tambi\u00e9n mantuvo sus sentimientos por el cartero  del Consejo estudiantil por a\u00f1os, aunque Haine pudo descubrirlos. <\/p>\n<p>Por todos sus secretos, y la profundidad de sus sentimientos por sus amigos, se gana el quinto lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit7\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>4. Fin Fish de Kamikaze Kaitou Jeanne<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Fin-Fish-Kamikaze-Kaitou-Jeanne-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"351\" height=\"500\" class=\"aligncenter size-full wp-image-171110\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Fin-Fish-Kamikaze-Kaitou-Jeanne-manga.jpg 351w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Fin-Fish-Kamikaze-Kaitou-Jeanne-manga-150x214.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Fin-Fish-Kamikaze-Kaitou-Jeanne-manga-300x427.jpg 300w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4088551478\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes:  7 <\/li>\n<li>Publicaci\u00f3n:  1997 - 2000 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\nFinn Fish es el \u00e1ngel de pelo verde que se apareci\u00f3 frente a Maron Kusakabe para revelarle su destino como la reencarnaci\u00f3n de Jeanne D\u00b4Arc. Es un \u00e1ngel peque\u00f1o, que no es considerada un \u00e1ngel completo, pero est\u00e1 bastante cerca de ello pues sus alas son blancas  y no negras. Tambi\u00e9n es la primera amiga de verdad de Maron, y la ayuda y la apoya en su misi\u00f3n de salvar la belleza de los corazones humanos. Lamentablemente es s\u00f3lo una mentira. La verdad es que Fin es la  abogada del diablo y su trabajo es lastimar a Maron y llenar su coraz\u00f3n de maldad para que los poderes de Jeanne D\u00b4Arc desaparezcan para siempre. <\/p>\n<p>S\u00f3lo eso es suficiente para que Fin califique para nuestra lista porque no es una traidora: Es una esp\u00eda. Y es muy buena en su trabajo, pues logra manipular a Maron, Chiaki y Access Time de manera perfecta. Pero entonces nos enteramos por qu\u00e9 decidi\u00f3 volverse una esp\u00eda, por qu\u00e9 traicion\u00f3 al cielo y se fue a trabajar con Maou para destruir el trabajo de la reencarnaci\u00f3n de Eva. Y esa historia es tan tr\u00e1gica y rompe el coraz\u00f3n de tal manera que merecer\u00eda un manga para ella s\u00f3la. Es cuando nos damos cuenta de que la chica que traicion\u00f3 al cielo antes fue traicionada por todos a su alrededor, excepto por Access Time.<\/p>\n<p>Por su pasado tr\u00e1gico, Finn se gana el cuarto lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit8\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>3. Kyoko Sumoi de Time Stranger Kyoko<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/10\/Time-Stranger-Kyoko-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"333\" height=\"499\" class=\"aligncenter size-full wp-image-102385\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/10\/Time-Stranger-Kyoko-manga.jpg 333w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/10\/Time-Stranger-Kyoko-manga-150x225.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/10\/Time-Stranger-Kyoko-manga-300x450.jpg 300w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.com\/dp\/1421517973\/?tag=hone01d-20\" target=\"_blank\" rel=\"noopener\"><i class=\"fa fa-fw fa-amazon\"><\/i>Buy now<\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 3 <\/li>\n<li>Publicaci\u00f3n:  2000 -2001 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Kyoko<\/strong> es la princesa de la Tierra. Con ese t\u00edtulo, es f\u00e1cil pensar que su vida es de lujos y sin problemas, pero la verdad es que ella prefiere vivir como una persona com\u00fan, sin que nadie sepa que es parte de la familia real.  Si, dos guardaespaldas la siguen constantemente, pero son capaces de mezclarse con los estudiantes de la escuela y fingen ser sus amigos. As\u00ed, puede vivir feliz incluso si la gente a su alrededor est\u00e1 algo ansiosa de ver a su princesa y futura gobernante. As\u00ed que el padre de Kyoko, el rey, le ofrece un trato: si logra despertar a su hermana gemela, Ul, que est\u00e1 dormida fuera del tiempo, Ul ser\u00e1 la futura reina y Kyoko podr\u00e1 seguir su vida como quiera. <\/p>\n<p>Si hablamos de su personalidad, Kyoko es una chica muy alegre, leal y amistosa. Es, despu\u00e9s de todo, un personaje principal de un shoujo. Tiene su coraz\u00f3n visible y al frente, y quiere despertar a su hermana no s\u00f3lo para poder vivir libre como una chica normal, sino para hablar con la hermana que nunca tuvo la oportunidad de conocer. Tambi\u00e9n es capaz de sacrificar su felicidad por la felicidad de sus amigos y, lo m\u00e1s importante, tiene una historia que es un secreto hasta de s\u00ed misma porque no sabe que en realidad no es humana, sino la hija de <strong>Chronos<\/strong>, el Dios del Tiempo. <\/p>\n<p>Y esa es la raz\u00f3n por la que Kyoko, a pesar de no ser la m\u00e1s conocida de los personajes de <em>Arina Tanemura<\/em>, se gana el tercer lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit9\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>2. Ai Tachibana de Neko to Watashi no Kinyobi<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Ai-Tachibana-Neko-to-Watashi-no-Kinyobi-manga-300x472.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"300\" height=\"472\" class=\"aligncenter size-witdh-300 wp-image-171112\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Ai-Tachibana-Neko-to-Watashi-no-Kinyobi-manga-300x472.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Ai-Tachibana-Neko-to-Watashi-no-Kinyobi-manga-150x236.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Ai-Tachibana-Neko-to-Watashi-no-Kinyobi-manga.jpg 318w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/4088450566\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes: 11 <\/li>\n<li>Publicaci\u00f3n:  2013 \u2013 2015 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Ai Tachibana<\/strong> es una chica muy dulce de 16 a\u00f1os. Es considerada como exageradamente femenina, y eso resuena en su forma de vestir, su cabello rosa, y el hecho de que ama todas las cosas que son tiernas, y en particular, el chocolate. Tambi\u00e9n tiene dos grandes amores en su vida, su familia, y uno de sus compa\u00f1eros de clase, <strong>Mia Serizawa<\/strong>. Ai est\u00e1 segura que Mia corresponde sus sentimientos, pero como \u00e9l no  da el primer paso de pedirle que salgan, ella supone que es necesario que ella le diga c\u00f3mo se siente por \u00e9l, aunque no tiene idea de c\u00f3mo hacerlo. <\/p>\n<p>Al mismo tiempo, e incluso si no es la mejor estudiante de su clase, est\u00e1 sirviendo como tutora para su primo <strong>Nekota<\/strong>, que est\u00e1 en la primaria. Por alguna raz\u00f3n, Nekota siempre est\u00e1 cerca cuando Ai trata de hablar con Serizawa, y en general arruina cualquier intento que Ai hace para revelar sus sentimientos. Es entonces cuando Ai descubre la verdad: Nekota est\u00e1 enamorado de ella, y no va a dejar que nadie se interponga en su camino para conquistarla. Por lo que ahora Ai tiene que convencer a su primo de que lo suyo no puede ser, mientras que ella analiza c\u00f3mo se siente por Mia\u2026 y c\u00f3mo se siente por Nekota. <\/p>\n<p>Por su forma de verse, y por la novedad de ver a una chica mayor ser perseguida por un chico mucho m\u00e1s joven, le damos a Ai el segundo lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-unit\" id=\"scroll-character-unit10\">\n<h1>\n    <i class=\"fa fa-fw fa-github-alt\"><\/i>1. Maron Kusakabe de Kamikaze Kaitou Jeanne<br \/>\n  <\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maron-Kusakabe-Kamikaze-Kaitou-Jeanne-manga.jpg\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" width=\"328\" height=\"500\" class=\"aligncenter size-full wp-image-171113\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maron-Kusakabe-Kamikaze-Kaitou-Jeanne-manga.jpg 328w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maron-Kusakabe-Kamikaze-Kaitou-Jeanne-manga-150x229.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/08\/Maron-Kusakabe-Kamikaze-Kaitou-Jeanne-manga-300x457.jpg 300w\" sizes=\"(max-width: 328px) 100vw, 328px\" \/>\n      <\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/408321211X\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<ul class=\"text-gray mt30\">\n<li>Vol\u00famenes:  7 <\/li>\n<li>Publicaci\u00f3n:  1997 - 2000 <\/li>\n<\/ul>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Maron Kusakabe<\/strong> parece ser una chica muy activa y alegre. Es muy amiga de su vecina y compa\u00f1era de clase <strong>Miyako Toudaiji<\/strong>. Todos en la escuela saben que Maron es una chica c\u00e1lida, que siempre sonr\u00ede y est\u00e1 dispuesta a ayudar. Sin embargo, tambi\u00e9n esconde una terrible depresi\u00f3n, causada el hecho de que ha vivido sola durante a\u00f1os mientras sus padres divorciados trabajan en el extranjero, y ella a\u00fan no decide con quien quiere vivir. Tambi\u00e9n tiene otro secreto: gracias a su amiga, el \u00e1ngel en entrenamiento <strong>Finn Fish<\/strong>, puede transformarse en <strong>Kaitou Jeanne<\/strong>, una chica m\u00e1gica cuya misi\u00f3n es salvar la belleza de los corazones humanos de los demonios que buscan destruirla. <\/p>\n<p>Pero lo que hace a Maron interesante no es su doble vida como la ladrona fantasma. No, es la dualidad de c\u00f3mo esconde su depresi\u00f3n y su soledad. Quiere confiar en <strong>Chaiki<\/strong>, pero sus experiencias con el amor la hacen temer hacerlo. Ama a su amiga Miyako, pero tiene miedo de lastimarla porque Miyako quiere capturar a Jeanne. Y claro, ama a sus padres, a ambos, y tiene mucho miedo de que ya no la amen, por lo que no puede llamarlos para preguntar porque nunca le escriben (No sabe que de hecho, todo es un plan para que se desespere m\u00e1s, y pierda sus poderes como el viento de dios) <\/p>\n<p>La forma en que Maron balancea todo lo que pasa a su alrededor, y la revelaci\u00f3n de sus or\u00edgenes y porque es importante que se recupere de todo ese dolor, es la raz\u00f3n por la que tiene el primer lugar de nuestra lista. <\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.wrap-unit --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<h2>Palabras finales<\/h2>\n<div id=\"scroll-character-end\">\n<p>\nLo que hace que un personaje sea interesante y bien dise\u00f1ado puede resumirse en lo que cada lector prefiere. Como la belleza, est\u00e1 en quien la observa. Sin embargo hay algunas cualidades que hacen que los personajes sobresalgan del resto: tanto en apariencia como en personalidad.<\/p>\n<p>Como dijimos al principio, <em>Arina Tanemura<\/em> es famosa por sus historias shoujo. Pero mas que eso, sus personajes siempre tienen profundidades ocultas. Incluso los romances m\u00e1s dulces no son lo que parecen. As\u00ed que les preguntamos \u00bfEst\u00e1n de acuerdo con nuestra lista? \u00bfO nos falt\u00f3 alguno de sus personajes m\u00e1s interesantes que merece estar aqu\u00ed? Por favor, d\u00e9jenoslo saber en los comentarios. <\/p>\n<\/div>\n<div class=\"wrap-author well mt60\" id=\"wrap-author-071\">\n<div class=\"row\">\n<div class=\"col-xs-12 col-sm-4 col-md-3\">\n<div class=\"wrap-author-image pull-left mr15\">\n<div class=\"author-box\">\n<div class=\"wrap-centered\">\n<div class=\"wrap-centered-content\">\n<div class=\"wrap-img-overlay\"><img src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/img-common\/author-profile-image\/071.jpg\" width=\"120px\" height=\"120px\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\"><\/p>\n<div class=\"wrap-text-overlay overlay-\">\n<p class=\"sfont text-overlay\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clearfix hidden-xs\"><\/div>\n<p class=\"author-social mt10 mb0 mt6-xs\"><a href=\"https:\/\/www.facebook.com\/AdalisaZ\" target=\"_blank\" rel=\"noopener\" aria-label=\"link to author facebook\"><i class=\"fa fa-facebook\"><\/i><\/a><\/p>\n<\/div>\n<div class=\"col-xs-12 col-sm-8 col-md-9\">\n<div>\n<p><i class=\"fa fa-fw fa-pencil\"><\/i>Autor: <em>Adalisa Zarate<\/em><\/p>\n<\/div>\n<div>\n<p class=\"author-profile fz9\">\n<p class=\"fz9\"><a href=\"https:\/\/honeysanime.com\/es\/author\/adalisa-zarate\/\"><i class=\"fa fa-fw fa-pencil\"><\/i>Art\u00edculos escritos<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-ad ad-bottom mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Bottom_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/los-10-mejores-mangas-de-leiji-matsumoto\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"295\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/03\/Matsumoto-Leiji-no-sekai-Wallpaper-300x295.jpg\" class=\"attachment-medium size-medium wp-post-image\"alt = \"time-stranger-kyoko-manga Los 10 mejores personajes dise\u00f1ados por Arina Tanemura\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/03\/Matsumoto-Leiji-no-sekai-Wallpaper-300x295.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/03\/Matsumoto-Leiji-no-sekai-Wallpaper-150x147.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/03\/Matsumoto-Leiji-no-sekai-Wallpaper.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/los-10-mejores-mangas-de-leiji-matsumoto\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Los 10 mejores mangas de Leiji Matsumoto<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-recommended-post well \">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/los-10-mejores-mangas-de-rumiko-takahashi\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Los 10 mejores mangas de Rumiko Takahashi<\/a><\/h3>\n<\/div>\n<div class=\"wrap-recommended-post well \">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/los-10-mejores-mangas-de-junji-ito\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Los 10 mejores mangas de Junji Ito<\/a><\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arina Tanemura es una conocida artista de manga que se ha hecho f\u00e1cilmente reconocible por su estilo detallado de dibujo y su inteligente uso de la pantalla de tonos. Desde su primera serie, I.O.N., tambi\u00e9n ha hecho renombre como escritora de historias rom\u00e1nticas que tienen un poquito extra de misterio, y a veces hasta finales [&hellip;]<\/p>\n","protected":false},"author":839,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[155,265],"tags":[230,229],"themes":[738,859,921],"display":[],"seasonal":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5dDBg-J1Z","_links":{"self":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/173103"}],"collection":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/users\/839"}],"replies":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/comments?post=173103"}],"version-history":[{"count":3,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/173103\/revisions"}],"predecessor-version":[{"id":173266,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/173103\/revisions\/173266"}],"wp:attachment":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media?parent=173103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/categories?post=173103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/tags?post=173103"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/themes?post=173103"},{"taxonomy":"display","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/display?post=173103"},{"taxonomy":"seasonal","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/seasonal?post=173103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}