{"id":58520,"date":"2016-02-15T03:47:25","date_gmt":"2016-02-15T08:47:25","guid":{"rendered":"http:\/\/honeysanime.com\/es\/?p=58520"},"modified":"2017-11-16T03:01:12","modified_gmt":"2017-11-16T08:01:12","slug":"los-5-personajes-del-anime-mas-psicoticos","status":"publish","type":"post","link":"https:\/\/honeysanime.com\/es\/los-5-personajes-del-anime-mas-psicoticos\/","title":{"rendered":"Los 5 personajes del anime m\u00e1s psic\u00f3ticos"},"content":{"rendered":"<p><!-- \n\n<div class=\"wrap-ad ad-top1 mb40\">[pc]\n\n<div class=\"unit-ad\">[ad_pc_article_top1_1]<\/div>\n\n\n\n<div class=\"unit-ad\">[ad_pc_article_top1_2]<\/div>\n\n[\/pc][sp][ad_sp_article_top1_1][\/sp]<\/div>\n\n --><\/p>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper-700x499.jpg\"alt = \"Mirai-Nikkii-Wallpaper-700x499 Los 5 personajes del anime m\u00e1s psic\u00f3ticos\" width=\"700\" height=\"499\" class=\"aligncenter size-width-700 wp-image-78045\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper-150x107.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper-300x214.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper-500x356.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/05\/Mirai-Nikkii-Wallpaper-560x399.jpg 560w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t<\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/B00932N1ZW\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/div>\n<div class=\"mt40\">\n<p>\n\u00bfAlguna vez te preguntaste qu\u00e9 se necesita para ser incluido en una lista de personas con psicosis pura? Bueno, tienes que tener una sobrecarga de cosas que no est\u00e1n bien, completamente atrapado por el dolor y el sufrimiento de los dem\u00e1s hasta el punto de sentirte en puro \u00e9xtasis. Tienes que estar mal al punto que todo el mundo te ve y no puede pensar ni una cosa buena de t\u00ed de tan jodida que tienes la cabeza. Tu tenebrosa obsesi\u00f3n te controla la vida y dicta todo lo que haces.<\/p>\n<p>Esos son los criterios para llegar a una lista de personas que est\u00e1n realmente retorcidos, sin ninguna exageraci\u00f3n, \u00a1aqu\u00ed est\u00e1 mi lista de personajes que tienen que ver para creer!\n\t<\/p>\n<\/div>\n<div class=\"wrap-ad ad-top2 mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Top_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<div class=\"unit-anime\">\n<h1 class=\"mt40\">\n\t\t<i class=\"fa fa-fw fa-github-alt\"><\/i>5. Shion Sonozaki de When They Cry<br \/>\n\t\t[Japon\u00e9s: Higurashi no Naku Koro ni]<br \/>\n\t<\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-300x427.jpg\"alt = \"Mirai-Nikkii-Wallpaper-700x499 Los 5 personajes del anime m\u00e1s psic\u00f3ticos\" width=\"300\" height=\"427\" class=\"aligncenter size-witdh-300 wp-image-163787\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-300x427.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-150x213.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-768x1092.jpg 768w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-500x711.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-352x500.jpg 352w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-700x996.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion-560x796.jpg 560w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/07\/Higurashi-no-Naku-Koro-Ni-manga-Shion.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n<\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/B009UP35RG\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nDefine demente y eso es lo que se obtiene de este anime. Todo el mundo muere, nadie vive. De vez en cuando se ve un lado aterrador de los personajes principales, pero ninguno se destac\u00f3 m\u00e1s que <strong>Shion<\/strong>. Su intensa presi\u00f3n, sus ojos dementes y absolutamente horribles, todo acerca de este personaje psic\u00f3tico es aterrador.<\/p>\n<p>Para explicarte por qu\u00e9 se volvi\u00f3 psic\u00f3tica, ella estaba enamorada de <strong>Satoshi<\/strong>, quien un d\u00eda desaparece, ella culpa a las tres familias de<em> Hinamizawa<\/em> por su desaparici\u00f3n. A causa de su dolor por perder al chico que amaba, ella manifiesta una personalidad s\u00e1dica (incluso se podr\u00eda decir demon\u00edaca) y comenz\u00f3 una masacre una detr\u00e1s de otra.<\/p>\n<p>Esto es definitivamente un personaje que debes ver para sentirte bien de ti mismo, porque \u00a1No te puedes poner m\u00e1s retorcido que esto!\n\t\t<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.unit-anime --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"unit-anime\">\n<h1 class=\"mt40\">\n\t\t<i class=\"fa fa-fw fa-github-alt\"><\/i>4. Accelerator de A Certain Magical Index<br \/>\n\t\t[Japon\u00e9s: Toaru Majutsu no Index]<br \/>\n\t<\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<img loading=\"lazy\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/accelerator-toaru-majutsu-no-index-Wallpaper-300x439.jpg\"alt = \"Mirai-Nikkii-Wallpaper-700x499 Los 5 personajes del anime m\u00e1s psic\u00f3ticos\" width=\"300\" height=\"439\" class=\"aligncenter size-witdh-300 wp-image-136407\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/accelerator-toaru-majutsu-no-index-Wallpaper-300x439.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/accelerator-toaru-majutsu-no-index-Wallpaper-150x219.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2017\/04\/accelerator-toaru-majutsu-no-index-Wallpaper.jpg 342w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t<\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><a href=\"http:\/\/www.amazon.co.jp\/dp\/B004P8DDMU\" target=\"_blank\" rel=\"noopener\">amazon jp<i class=\"fa fa-external-link ml5\"><\/i><\/a><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\nSiendo el ps\u00edquico m\u00e1s poderoso en <em>Academy City<\/em>; tanto es as\u00ed que tiene que permitir conscientemente que la gravedad lo afecte, <strong>Accelerator<\/strong> no es alguien con quien quieras meterte. Mezcla estos hechos con una personalidad s\u00e1dica y terminas con una receta para el desastre. \u00c9l incluso puede cambiar la direcci\u00f3n del flujo sangu\u00edneo en el cuerpo de otra persona para matarlos.<\/p>\n<p>Tom\u00f3 parte en un experimento para convertirse en el primer <em>Esper<\/em> nivel 6 del mundo. Debido a que s\u00f3lo se conoc\u00edan otras 6 personas de nivel 5, se encarg\u00f3 de matar a 20,000 otras personas de nivel de 3 y lo hizo con gusto y felizmente.<\/p>\n<p>\u00bfQu\u00e9 opinas acerca de un chico que est\u00e1 m\u00e1s que dispuesto a matar a 20,000 personas para ser m\u00e1s fuerte? De seguro piensas que es un hueco profundo dentro de la psicosis.\n\t\t<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.unit-anime --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"unit-anime\">\n<h1 class=\"mt40\">\n\t\t<i class=\"fa fa-fw fa-github-alt\"><\/i>3. Berg-Katze de Gatchaman Crowds<br \/>\n\t<\/h1>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Berg<\/strong> no es tu loco\/ a \"com\u00fan\"; \u00e9l \/ ella est\u00e1 en un nivel completamente diferente de sadismo. Su principal objetivo es poner a todos en el universo uno contra el otro, para que en \u00faltima instancia se maten entre s\u00ed mismos. \u00c9l \/ Ella es andr\u00f3gina, lo que significa que no se puede saber su g\u00e9nero aunque eso comparado con lo que hace no importa en lo absoluto.<\/p>\n<p>Con el poder de transformarse en cualquier persona que Berg bese, se disfraza para estafar a las personas por todo tipo de cr\u00edmenes.<\/p>\n<p>Lo que pone a Berg en la lista de personajes psic\u00f3ticos no es s\u00f3lo porque est\u00e1 loco, es: qu\u00e9 tan loco. Nunca ensucia sus propias manos, pero obliga a los dem\u00e1s sin que ellos lo sepan. \u00a1Ese nivel de manipulaci\u00f3n es el sue\u00f1o de un fan de psicolog\u00eda!\n\t\t<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.unit-anime --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-ad ad-middle \">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Middle_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<div class=\"unit-anime\">\n<h1 class=\"mt40\">\n\t\t<i class=\"fa fa-fw fa-github-alt\"><\/i>2. Yuno Gasai de Future Diary<br \/>\n\t\t[Japon\u00e9s: Mirai Nikki]<br \/>\n\t<\/h1>\n<div align=\"center\">\n<div class=\"inline-block\">\n<div class=\"img-shadow\">\n<aside class=\"exclude-from-excerpt\">\n<div class=\"twitter-tweet\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"ja\" dir=\"ltr\">\u672a\u6765\u65e5\u8a18\u30d1\u30c1\u30b9\u30ed\u3067\u3059\u304c<br \/>\u65b0\u898f\u30d3\u30b8\u30e5\u30a2\u30eb\uff06\u30dc\u30a4\u30b9\u306b\u3082\u6ce8\u76ee\u3067\u3059\uff01<br \/>\u672a\u6765\u65e5\u8a18\u30d5\u30a1\u30f3\u306a\u3089\u898b\u9003\u305b\u306a\u3044\u6f14\u51fa\u3082\uff01<br \/>\u8a73\u3057\u304f\u306f\u7279\u8a2d\u30b5\u30a4\u30c8\u306b\u3066<a href=\"https:\/\/t.co\/QhIS5RqFgD\">https:\/\/t.co\/QhIS5RqFgD<\/a><a href=\"https:\/\/twitter.com\/hashtag\/mirainikki?src=hash&amp;ref_src=twsrc%5Etfw\">#mirainikki<\/a> <a href=\"https:\/\/t.co\/ZX4pRhs9TI\">pic.twitter.com\/ZX4pRhs9TI<\/a><\/p>\n<p>&mdash; \u30a2\u30cb\u30e1\u300c\u30d3\u30c3\u30b0\u30aa\u30fc\u30c0\u30fc\u300d\uff06\u300c\u672a\u6765\u65e5\u8a18\u300d (@mirai_nikki) <a href=\"https:\/\/twitter.com\/mirai_nikki\/status\/763277517725708288?ref_src=twsrc%5Etfw\">10 de agosto de 2016<\/a><\/p><\/blockquote>\n<\/div>\n<\/aside><\/div>\n<aside class=\"exclude-from-excerpt source-link\">\n<div class=\"wrap-source-link  \"><\/div>\n<\/aside><\/div>\n<\/p><\/div>\n<div class=\"wrap-paragraph mt30\">\n<p>\n<strong>Yuno <\/strong>es posiblemente el personaje m\u00e1s retorcido que he visto personalmente en cualquier anime. Ella va m\u00e1s all\u00e1 de asesinatos psico-trastornados, sino que tambi\u00e9n es acosadora y secuestradora profesional. Tiene una obsesi\u00f3n a otro nivel con el personaje principal <strong>Yukiteru<\/strong> e incluso le lava el cerebro en m\u00e1s de una ocasi\u00f3n. Se detiene ante nada para estar con \"Yuki\", es decir que desde antes lo ha secuestrado y lo ha atado a una silla, le da de comer e incluso lo ayuda a usar el ba\u00f1o, nunca soltandolo de la silla.<\/p>\n<p>Acoplando esta obsesi\u00f3n con el conocimiento de que est\u00e1n en un peligroso juego de \"matar al resto,\" ella muestra sus verdaderos colores en m\u00e1s de una ocasi\u00f3n. Asesina a cualquiera que se interponga en el camino entre ella y Yuki, yendo tan lejos como matar a la madre de Yuki si no le cae bien.<\/p>\n<p>Ella logr\u00f3 este nivel tremendo de psicosis gracias a su propia madre, que la encerraba en una jaula cada vez que le daba la gana. Cuando no se le permita salir de la jaula, se ver\u00eda obligada a orinarse y defecarse encima, y a menudo la dejaban sin comer. Un libro de texto no bastar\u00eda para definir su obsesi\u00f3n, lo que tendr\u00eda a los psic\u00f3logos ocupados durante a\u00f1os tratando de averiguar qu\u00e9 es exactamente lo que se necesita hacer para ayudarla.<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.unit-anime --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"unit-anime\">\n<h1 class=\"mt40\">\n\t\t<i class=\"fa fa-fw fa-github-alt\"><\/i>1. Liang Qi de Canaan<br \/>\n\t<\/h1>\n<div class=\"wrap-paragraph mt30\">\n<p>\nEste es un personaje muy divertido de ver, sobre todo porque no luce tan loca como lo es. Al menos no hasta que descubres su extrema obsesi\u00f3n con su comandante, que ella llama \"Onee-san\" (hermana mayor).<\/p>\n<p>En una pelea que tuvo con su comandante (<strong>Alphard<\/strong>), cuando la cortan ella grita, \"Duele ... Duele hermana, m\u00e1s, \u00a1haz que duela m\u00e1s!\"<\/p>\n<p>Dime que eso no es una locura. Durante toda la serie ha demostrado ser altamente implacable con una actitud muy devota hacia Alphard. Su obsesi\u00f3n la lleva a hacer estos actos atroces, con la cara de una loca y la sonrisa de un asesino.<\/p>\n<\/p><\/div>\n<\/div>\n<p><!-- \/.unit-anime --><\/p>\n<hr class=\"hr-dashed mt40 mb40\">\n<h2>Palabras finales<\/h2>\n<div>\n<p>\n\u00a1Aqu\u00ed termina mi lista de personajes psic\u00f3ticos favoritos! Si tienes cualquier otra recomendaci\u00f3n por favor d\u00e9jala en la secci\u00f3n de comentarios y \u00a1dime lo que piensas! Cr\u00e9anme cuando digo que siempre hay tiempo para un poco de locura en nuestras vidas.\n\t<\/p>\n<\/div>\n<div class=\"mt40\">Por <em>Nathaniel Loomis<\/em><\/div>\n<div class=\"mt20\">Traducido por: <em>Yanayme Roman<\/em><\/div>\n<div class=\"wrap-ad ad-bottom mt40\">\n<div class=\"mt20 mb20 pr0-xs pl0-xs flexbox justify-content-center\">\n<div class=\"unit-ad\">\n<div class=\"ad-tag\" data-ad-name=\"Sortable_HoneysAnime_Desktop_Bottom_728x90\" data-ad-size=\"728x90\" ><\/div>\n<p><script src=\"\/\/tags-cdn.deployads.com\/a\/blog.honeyfeed.fm.js\" async ><\/script><br \/>\n<script>(deployads = window.deployads || []).push();<\/script><\/div>\n<div class=\"unit-ad mt40-xs\"><!-- temp --> <\/div>\n<\/div>\n<\/div>\n<hr class=\"hr-dashed mt40 mb40\">\n<div class=\"wrap-recommended-post well \">\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<div class=\"overflow-hidden wrap-center-hv\" style=\"height: 180px;\"><a href=\"https:\/\/honeysanime.com\/es\/los-10-personajes-mas-antisociales-del-anime\/\" class=\"hover-zoom\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');><img width=\"300\" height=\"218\" src=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-300x218.jpg\" class=\"attachment-medium size-medium wp-post-image\"alt = \"Mirai-Nikkii-Wallpaper-700x499 Los 5 personajes del anime m\u00e1s psic\u00f3ticos\" loading=\"lazy\" srcset=\"https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-300x218.jpg 300w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-150x109.jpg 150w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-500x364.jpg 500w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-688x500.jpg 688w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper.jpg 700w, https:\/\/honeysanime.com\/wp-content\/uploads\/2016\/04\/Psycho-Pass-Wallpaper-560x407.jpg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<\/div>\n<div class=\"col-sm-6\">\n<p><i class=\"fa fa-fw fa-github-alt\"><\/i>Entrada recomendada<\/p>\n<h3><a href=\"https:\/\/honeysanime.com\/es\/los-10-personajes-mas-antisociales-del-anime\/\" onClick=ga('send','event','link','click','to_recommended_post_@post_insert');>Los 10 personajes m\u00e1s antisociales del anime<\/a><\/h3>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te preguntaste qu\u00e9 se necesita para ser incluido en una lista de personas con psicosis pura? Bueno, tienes que tener una sobrecarga de cosas que no est\u00e1n bien, completamente atrapado por el dolor y el sufrimiento de los dem\u00e1s hasta el punto de sentirte en puro \u00e9xtasis. Tienes que estar mal al punto [&hellip;]<\/p>\n","protected":false},"author":672,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[155],"tags":[],"themes":[797,796,738],"display":[],"seasonal":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5dDBg-fdS","_links":{"self":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/58520"}],"collection":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/users\/672"}],"replies":[{"embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/comments?post=58520"}],"version-history":[{"count":5,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/58520\/revisions"}],"predecessor-version":[{"id":164293,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/posts\/58520\/revisions\/164293"}],"wp:attachment":[{"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/media?parent=58520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/categories?post=58520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/tags?post=58520"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/themes?post=58520"},{"taxonomy":"display","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/display?post=58520"},{"taxonomy":"seasonal","embeddable":true,"href":"https:\/\/honeysanime.com\/es\/wp-json\/wp\/v2\/seasonal?post=58520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}